{"id":3611,"date":"2023-01-17T12:58:39","date_gmt":"2023-01-17T12:58:39","guid":{"rendered":"https:\/\/elperiodicoky.com\/?p=3611"},"modified":"2023-01-17T12:58:41","modified_gmt":"2023-01-17T12:58:41","slug":"dhs-anuncia-mejoras-para-proteger-a-los-trabajadores-no-ciudadanos-y-evitar-abusos","status":"publish","type":"post","link":"https:\/\/elperiodicoky.com\/index.php\/2023\/01\/17\/dhs-anuncia-mejoras-para-proteger-a-los-trabajadores-no-ciudadanos-y-evitar-abusos\/","title":{"rendered":"<strong>DHS anuncia mejoras para proteger a los trabajadores no ciudadanos y evitar abusos<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Departamento de Seguridad Nacional de Estados Unidos (DHS) ha anunciado que los trabajadores no ciudadanos que son v\u00edctimas o testigos de violaci\u00f3n de los derechos laborales ahora pueden acceder a un proceso simplificado y acelerado para solicitar acci\u00f3n diferida. La acci\u00f3n diferida protege a los trabajadores no ciudadanos de las amenazas de represalias relacionadas con la inmigraci\u00f3n por parte de los empleadores explotadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los trabajadores podr\u00e1n visitar DHS.gov para obtener informaci\u00f3n adicional en ingl\u00e9s y espa\u00f1ol y presentar solicitudes. Estas mejoras promueven el compromiso de la Administraci\u00f3n Biden-Harris de empoderar a los trabajadores y mejorar las condiciones del lugar de trabajo, al permitir que todos los trabajadores, incluidos los no ciudadanos, hagan valer sus derechos legales. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(Comunicado del USCIS)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Seguridad Nacional de Estados Unidos (DHS) ha anunciado que los trabajadores no ciudadanos que son v\u00edctimas o testigos de violaci\u00f3n de los derechos laborales ahora pueden acceder a un proceso simplificado y acelerado para solicitar acci\u00f3n diferida. La acci\u00f3n diferida protege a los trabajadores no ciudadanos de las amenazas de represalias relacionadas con la inmigraci\u00f3n por parte de los empleadores explotadores. Los trabajadores podr\u00e1n visitar DHS.gov para obtener informaci\u00f3n adicional en ingl\u00e9s y espa\u00f1ol y presentar solicitudes. Estas mejoras promueven el compromiso de la Administraci\u00f3n Biden-Harris de&hellip;<\/p>\n","protected":false},"author":2,"featured_media":3612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-3611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/elperiodicoky.com\/wp-content\/uploads\/2023\/01\/80.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/posts\/3611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/comments?post=3611"}],"version-history":[{"count":1,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/posts\/3611\/revisions"}],"predecessor-version":[{"id":3613,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/posts\/3611\/revisions\/3613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/media\/3612"}],"wp:attachment":[{"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/media?parent=3611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/categories?post=3611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/tags?post=3611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}