{"id":3697,"date":"2023-02-01T16:16:42","date_gmt":"2023-02-01T16:16:42","guid":{"rendered":"https:\/\/elperiodicoky.com\/?p=3697"},"modified":"2023-02-01T16:16:42","modified_gmt":"2023-02-01T16:16:42","slug":"uscis-redisena-las-tarjetas-de-residente-permanente-y-los-documentos-de-autorizacion-de-empleo","status":"publish","type":"post","link":"https:\/\/elperiodicoky.com\/index.php\/2023\/02\/01\/uscis-redisena-las-tarjetas-de-residente-permanente-y-los-documentos-de-autorizacion-de-empleo\/","title":{"rendered":"USCIS Redise\u00f1a las Tarjetas de Residente Permanente y los Documentos de Autorizaci\u00f3n de Empleo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (USCIS) anunci\u00f3 nuevos dise\u00f1os para mejorar la seguridad de las Tarjetas de Residente Permanente (tambi\u00e9n conocidas como Green Cards o Tarjetas Verde) y los Documentos de Autorizaci\u00f3n de Empleo (EAD). USCIS comenz\u00f3 a emitir las tarjetas redise\u00f1adas el 30 de enero de 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los nuevos dise\u00f1os de las tarjetas de residente permanente y EAD contienen tecnolog\u00eda de vanguardia que contin\u00faa salvaguardando la seguridad nacional y mejora los servicios a nuestros clientes. Los cambios incluyen ilustraciones detalladas actualizadas y mejoradas; impresi\u00f3n t\u00e1ctil que se integra mejor con el dise\u00f1o; tinta \u00f3ptica variable mejorada; im\u00e1genes hologr\u00e1ficas altamente seguras en la parte frontal y posterior de las tarjetas; una nueva funci\u00f3n de revelaci\u00f3n de capas con una ventana parcial en el cuadro de fotos posterior; y los campos de datos colocados en lugares diferentes a los de las versiones anteriores. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La introducci\u00f3n de los nuevos dise\u00f1os no significa que las tarjetas actuales emitidas no sean v\u00e1lidas. Las tarjetas actuales siguen siendo v\u00e1lidas hasta su fecha de vencimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunas tarjetas de residente permanente y EAD emitidos despu\u00e9s del 30 de enero de 2023 pueden mostrar el formato del dise\u00f1o actual porque USCIS continuar\u00e1 usando la cartulina existente hasta que se agoten los suministros actuales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(Comunicado publicado en el sitio web del USCIS el 30 de enero)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (USCIS) anunci\u00f3 nuevos dise\u00f1os para mejorar la seguridad de las Tarjetas de Residente Permanente (tambi\u00e9n conocidas como Green Cards o Tarjetas Verde) y los Documentos de Autorizaci\u00f3n de Empleo (EAD). USCIS comenz\u00f3 a emitir las tarjetas redise\u00f1adas el 30 de enero de 2023. Los nuevos dise\u00f1os de las tarjetas de residente permanente y EAD contienen tecnolog\u00eda de vanguardia que contin\u00faa salvaguardando la seguridad nacional y mejora los servicios a nuestros clientes. Los cambios incluyen ilustraciones detalladas actualizadas y mejoradas; impresi\u00f3n t\u00e1ctil&hellip;<\/p>\n","protected":false},"author":2,"featured_media":3698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-3697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/elperiodicoky.com\/wp-content\/uploads\/2023\/02\/Specimen-Green-card-2.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/posts\/3697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/comments?post=3697"}],"version-history":[{"count":1,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/posts\/3697\/revisions"}],"predecessor-version":[{"id":3699,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/posts\/3697\/revisions\/3699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/media\/3698"}],"wp:attachment":[{"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/media?parent=3697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/categories?post=3697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elperiodicoky.com\/index.php\/wp-json\/wp\/v2\/tags?post=3697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}